{"id":140,"date":"2016-04-21T11:51:07","date_gmt":"2016-04-21T09:51:07","guid":{"rendered":"http:\/\/newim.dii.unipd.it\/?page_id=140"},"modified":"2021-11-10T11:43:20","modified_gmt":"2021-11-10T10:43:20","slug":"trasferimenti","status":"publish","type":"page","link":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/","title":{"rendered":"Trasferimenti"},"content":{"rendered":"<div data-label=\"Content\" data-id=\"content--2\" data-export-id=\"content-17\" data-category=\"content\" class=\"content-17 content-section content-section-spacing dark-text\" id=\"content-2\" style=\"background-image: none;\" data-section-ov=\"1\">\r\n<div class=\"gridContainer\">\r\n<div class=\"row middle-sm\">\r\n<div class=\"col-sm-6 space-bottom-xs\" data-type=\"column\">\r\n<p class=\"\" style=\"text-align: justify;\">I Corsi di Studio in Ingegneria Aerospaziale favoriscono l\u2019iscrizione e i trasferimenti da parte di studenti che hanno conseguito la Laurea in Ingegneria Aerospaziale in altre Sedi o che stanno frequentando Corsi di Studio in discipline diverse dall\u2019Ingegneria Aerospaziale.\r\n\r\n\r\nL\u2019iscrizione al Corso di Laurea Magistrale in Ingegneria Aerospaziale \u00e8 subordinata al possesso dei requisiti curriculari richiesti per l\u2019accesso. Essi sono riportati nell\u2019 Avviso di ammissione della Scuola di Ingegneria, disponibile in\u00a0<a href=\"https:\/\/www.unipd.it\/trasferirsi-altro-ateneo\" target=\"_blank\" rel=\"noopener\" data-cp-link=\"1\" class=\"\">questa pagina,<\/a> nella quale \u00e8 descritta anche la procedura formale che gli interessati dovranno seguire per la preimmatricolazione e l\u2019eventuale richiesta ufficiale di Valutazione preventiva e riconoscimento crediti. Normalmente, il documento viene aggiornato una volta l\u2019anno, con congruo anticipo (luglio) rispetto alle scadenze per le procedure relative all\u2019anno accademico successivo.<\/p>\r\n\r\n<\/div>\r\n<div class=\"col-sm-6 flexbox around-xs top-xs space-top-xs space-bottom-xs\">\r\n<div class=\"overlay-box flexbox middle-xs center-xs overlay-holder\">\r\n<div class=\"overlay-box-offset offset-background shadow-medium bg-color2 hide-xs\"><\/div>\r\n<img decoding=\"async\" class=\"flexbox shadow-large img1\" data-size=\"500x500\" src=\"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/03\/cropped-anatomico_.jpg\" title=\"cropped-anatomico_.jpg\" alt=\"\" \/>\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<div data-label=\"Content\" data-id=\"content--3\" data-export-id=\"content-18\" data-category=\"content\" class=\"content-18 content-section content-section-spacing dark-text\" id=\"content-3\" style=\"background-image: none;\">\r\n<div class=\"gridContainer\">\r\n<div class=\"row middle-sm\">\r\n<div class=\"col-sm-6 flexbox around-xs top-xs space-bottom-xs space-top-xs\">\r\n<div class=\"overlay-box flexbox middle-xs center-xs overlay-holder\">\r\n<div class=\"overlay-box-offset offset-background shadow-medium bg-color2 hide-xs\"><\/div>\r\n<img decoding=\"async\" class=\"flexbox shadow-large img1\" data-size=\"500x500\" src=\"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/04\/imm.jpg\" title=\"imm\" alt=\"\" \/>\r\n\r\n<\/div>\r\n<\/div>\r\n<div class=\"col-sm-6\" data-type=\"column\">\r\n<p class=\"\" style=\"text-align: justify;\">I trasferimenti consentono di continuare presso l\u2019Universit\u00e0 di Padova gli studi iniziati in un altro Ateneo. La procedura formale e le scadenze sono descritte in <a href=\"https:\/\/www.unipd.it\/trasferirsi-altro-ateneo\" target=\"_blank\" rel=\"noopener\" data-cp-link=\"1\" class=\"\">questa pagina<\/a>, tuttavia gli interessati possono in qualunque momento ottenere una valutazione informale del proprio caso facendone richiesta alla Commissione Pratiche Studenti del Corso di Studio. Il parere della Commissione \u00e8 solo orientativo e non ufficiale; l\u2019unica deliberazione ufficiale \u00e8 infatti quella che viene fornita a seguito di presentazione di domanda ufficiale di valutazione dei requisiti curricolari minimi, secondo la procedura di Ateneo. La valutazione preventiva permette per\u00f2 di avere una risposta attendibile in tempi molto rapidi, in qualunque momento dell\u2019anno e senza alcuna spesa.<\/p>\r\n\r\n\r\nPer <span style=\"font-weight: bold;\">ottenere la valutazione informale<\/span>, i candidati devono inviare una e-mail al Presidente del CCS, <a href=\"mailto:ugo.galvanetto@unipd.it\" target=\"_blank\" rel=\"noopener\" data-cp-link=\"1\">Prof. Ugo Galvanetto<\/a>, con Oggetto \u201cTrasferimento studente Nome Cognome da Sede\u201d, nella quale va descritta la richiesta e vanno obbligatoriamente allegati:\r\n\u2013 il proprio piano di studio per il Corso di Laurea (triennale) e\/o Magistrale frequentati, indicando chiaramente i settori scientifico-disciplinari (SSD) degli insegnamenti e gli esami superati;\r\n\u2013 i programmi ufficiali con i contenuti di ciascuno degli insegnamenti.\r\nEventuali comunicazioni e-mail successive alla prima dovranno sempre riportare l\u2019intera storia dei messaggi e-mail gi\u00e0 intercorsi, per dar modo a chi legge (anche a distanza di tempo) di ricostruire immediatamente tutte le comunicazioni gi\u00e0 intercorse (usare cio\u00e8 sempre il tasto REPLY per tutte le e-mail successive alla prima inviata)\r\n\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>I Corsi di Studio in Ingegneria Aerospaziale favoriscono l\u2019iscrizione e i trasferimenti da parte di studenti che hanno conseguito la Laurea in Ingegneria Aerospaziale in altre Sedi o che stanno frequentando Corsi di Studio in discipline diverse dall\u2019Ingegneria Aerospaziale. L\u2019iscrizione al Corso di Laurea Magistrale in Ingegneria Aerospaziale \u00e8 subordinata al possesso dei requisiti curriculari&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":1001,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"pro\/page-templates\/full-width-page.php","meta":{"footnotes":""},"folder":[],"class_list":["post-140","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trasferimenti - Aerospace Engineering - Padova University<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trasferimenti - Aerospace Engineering - Padova University\" \/>\n<meta property=\"og:description\" content=\"I Corsi di Studio in Ingegneria Aerospaziale favoriscono l\u2019iscrizione e i trasferimenti da parte di studenti che hanno conseguito la Laurea in Ingegneria Aerospaziale in altre Sedi o che stanno frequentando Corsi di Studio in discipline diverse dall\u2019Ingegneria Aerospaziale. L\u2019iscrizione al Corso di Laurea Magistrale in Ingegneria Aerospaziale \u00e8 subordinata al possesso dei requisiti curriculari&hellip; Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/\" \/>\n<meta property=\"og:site_name\" content=\"Aerospace Engineering - Padova University\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-10T10:43:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/03\/cropped-a2b802fc59664d8a7ab93be091e05a24.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"970\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/\",\"url\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/\",\"name\":\"Trasferimenti - Aerospace Engineering - Padova University\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2021\\\/03\\\/cropped-a2b802fc59664d8a7ab93be091e05a24.png\",\"datePublished\":\"2016-04-21T09:51:07+00:00\",\"dateModified\":\"2021-11-10T10:43:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2021\\\/03\\\/cropped-a2b802fc59664d8a7ab93be091e05a24.png\",\"contentUrl\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2021\\\/03\\\/cropped-a2b802fc59664d8a7ab93be091e05a24.png\",\"width\":1456,\"height\":970,\"caption\":\"Trasferimenti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/trasferimenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/it\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trasferimenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/#website\",\"url\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/\",\"name\":\"Aerospace Engineering - Padova University\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/#organization\",\"name\":\"Dipartimento di Ingegneria Industriale Universit\u00e0 di Padova\",\"url\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2021\\\/11\\\/logo-UniPD-DII-final.png\",\"contentUrl\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/wp-content\\\/uploads\\\/sites\\\/50\\\/2021\\\/11\\\/logo-UniPD-DII-final.png\",\"width\":521,\"height\":102,\"caption\":\"Dipartimento di Ingegneria Industriale Universit\u00e0 di Padova\"},\"image\":{\"@id\":\"https:\\\/\\\/academics.dii.unipd.it\\\/aerospaceengineering\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trasferimenti - Aerospace Engineering - Padova University","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/","og_locale":"it_IT","og_type":"article","og_title":"Trasferimenti - Aerospace Engineering - Padova University","og_description":"I Corsi di Studio in Ingegneria Aerospaziale favoriscono l\u2019iscrizione e i trasferimenti da parte di studenti che hanno conseguito la Laurea in Ingegneria Aerospaziale in altre Sedi o che stanno frequentando Corsi di Studio in discipline diverse dall\u2019Ingegneria Aerospaziale. L\u2019iscrizione al Corso di Laurea Magistrale in Ingegneria Aerospaziale \u00e8 subordinata al possesso dei requisiti curriculari&hellip; Read more","og_url":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/","og_site_name":"Aerospace Engineering - Padova University","article_modified_time":"2021-11-10T10:43:20+00:00","og_image":[{"width":1456,"height":970,"url":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/03\/cropped-a2b802fc59664d8a7ab93be091e05a24.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/","url":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/","name":"Trasferimenti - Aerospace Engineering - Padova University","isPartOf":{"@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/#website"},"primaryImageOfPage":{"@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/#primaryimage"},"image":{"@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/#primaryimage"},"thumbnailUrl":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/03\/cropped-a2b802fc59664d8a7ab93be091e05a24.png","datePublished":"2016-04-21T09:51:07+00:00","dateModified":"2021-11-10T10:43:20+00:00","breadcrumb":{"@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/#primaryimage","url":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/03\/cropped-a2b802fc59664d8a7ab93be091e05a24.png","contentUrl":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/03\/cropped-a2b802fc59664d8a7ab93be091e05a24.png","width":1456,"height":970,"caption":"Trasferimenti"},{"@type":"BreadcrumbList","@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/trasferimenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/it\/homepage\/"},{"@type":"ListItem","position":2,"name":"Trasferimenti"}]},{"@type":"WebSite","@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/#website","url":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/","name":"Aerospace Engineering - Padova University","description":"","publisher":{"@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/#organization","name":"Dipartimento di Ingegneria Industriale Universit\u00e0 di Padova","url":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/#\/schema\/logo\/image\/","url":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/11\/logo-UniPD-DII-final.png","contentUrl":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-content\/uploads\/sites\/50\/2021\/11\/logo-UniPD-DII-final.png","width":521,"height":102,"caption":"Dipartimento di Ingegneria Industriale Universit\u00e0 di Padova"},"image":{"@id":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/pages\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/comments?post=140"}],"version-history":[{"count":17,"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/pages\/140\/revisions"}],"predecessor-version":[{"id":2414,"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/pages\/140\/revisions\/2414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/media\/1001"}],"wp:attachment":[{"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/media?parent=140"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/academics.dii.unipd.it\/aerospaceengineering\/wp-json\/wp\/v2\/folder?post=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}